{"id":41957,"date":"2018-04-07T14:01:03","date_gmt":"2018-04-07T11:01:03","guid":{"rendered":"https:\/\/dev.prestigtours.com\/analitika\/tyroperatory-rasskazali-kyda-rossiiane-poedyt-na-maiskie-prazdniki.html"},"modified":"2018-04-07T14:01:03","modified_gmt":"2018-04-07T11:01:03","slug":"tyroperatory-rasskazali-kyda-rossiiane-poedyt-na-maiskie-prazdniki","status":"publish","type":"post","link":"https:\/\/dev.prestigtours.com\/es\/analitika\/tyroperatory-rasskazali-kyda-rossiiane-poedyt-na-maiskie-prazdniki","title":{"rendered":"Los operadores tur\u00edsticos dijeron ad\u00f3nde ir\u00e1n los rusos durante las vacaciones de mayo"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2018\/04\/401781d5e1a5bce9c387eef2e0dc374e.jpg\" \/><\/p>\n<p><p>En particular, Marina Makarkova, directora del departamento de relaciones p\u00fablicas del operador tur\u00edstico Coral Travel, inform\u00f3 sobre el crecimiento de la popularidad de Turqu\u00eda en 50%. Turqu\u00eda tambi\u00e9n fue nombrada como destino l\u00edder por un amplio margen por las empresas Intourist, Tez Tour y Anex Tour.<\/p>\n<p>Los expertos se\u00f1alaron que <!--more-->El inter\u00e9s de los rusos por las vacaciones durante las fiestas de mayo ha aumentado en general. La compa\u00f1\u00eda Intourist inform\u00f3 que en el vuelo 69% se reservan viajes con m\u00e1s frecuencia que hace un a\u00f1o. Al mismo tiempo, la demanda en direcci\u00f3n nacional aument\u00f3 en 54% y en direcci\u00f3n internacional en 70%. Seg\u00fan la directora de relaciones p\u00fablicas del operador tur\u00edstico Tez Tour, Larisa Akhanova, este a\u00f1o las reservas para las vacaciones de mayo son mejores que las del a\u00f1o pasado.<\/p>\n<p><strong>Los rusos eligen playas extranjeras<\/strong><\/p>\n<p><strong><\/strong>Seg\u00fan los expertos, los destinos de playa extranjeros son los m\u00e1s populares entre los rusos que contactan con los operadores tur\u00edsticos para las pr\u00f3ximas vacaciones. Adem\u00e1s de Turqu\u00eda, los Emiratos \u00c1rabes Unidos, T\u00fanez, Tailandia y Grecia son muy populares. Al mismo tiempo, seg\u00fan M. Makarkova, en su empresa el volumen de ventas de viajes a T\u00fanez se ha m\u00e1s que duplicado, a pesar del aumento del precio medio en 7-8%. Tez Tour y Biblio-Globus informaron una gran demanda en Chipre. <\/p>\n<p>Entre los destinos de excursiones para las vacaciones de mayo los l\u00edderes son la Rep\u00fablica Checa, Italia y Espa\u00f1a. La compa\u00f1\u00eda Intourist tambi\u00e9n destac\u00f3 la popularidad de los viajes a los pa\u00edses b\u00e1lticos, y Biblio-Globus nombr\u00f3 a Bielorrusia como el destino de excursi\u00f3n m\u00e1s popular.<\/p>\n<p>Las vacaciones en Rusia durante las fiestas de mayo tienen menos demanda entre los operadores tur\u00edsticos. Entre los destinos nacionales m\u00e1s populares, Intourist mencion\u00f3 Sochi, Crimea, San Petersburgo, Mosc\u00fa, el Anillo de Oro y las Aguas Minerales del C\u00e1ucaso. El servicio de prensa del operador tur\u00edstico Biblio-Globus tambi\u00e9n inform\u00f3 sobre la popularidad de Gelendzhik, Anapa y Crimea.<\/p>\n<p><strong>\u00bfExiste demanda para Egipto?<\/strong><\/p>\n<p><strong><\/strong>A pesar de la reanudaci\u00f3n de los vuelos regulares de Mosc\u00fa a El Cairo el 11 de abril, ning\u00fan gran operador tur\u00edstico consultado por el portal Interfax-Turismo anunci\u00f3 la reanudaci\u00f3n de las ventas a Egipto. La \u00fanica excepci\u00f3n fue Tez Tour, que ofrece tours a centros tur\u00edsticos egipcios con traslados desde el aeropuerto de El Cairo desde mediados de marzo.<\/p>\n<p>Seg\u00fan L. Akhanova, varias decenas de clientes planean aprovechar la oferta durante las vacaciones de mayo. \u201cLa demanda super\u00f3 nuestras expectativas. Recibimos el mayor n\u00famero de reservas de Mosc\u00fa y San Petersburgo, y los hoteles en Hurghada son populares. \u201cQuiero recordarles que antes del cierre, Egipto era el l\u00edder en la carrera tur\u00edstica del Primero de Mayo\u201d, se\u00f1al\u00f3.<\/p>\n<p><strong>Los precios han subido, pero s\u00f3lo ligeramente.<\/strong><\/p>\n<p><strong><\/strong>Las empresas Coral Travel e Intourist se\u00f1alaron que en promedio el costo de un paquete tur\u00edstico ha aumentado en 10% en comparaci\u00f3n al a\u00f1o pasado. \u201cAl mismo tiempo, muchos destinos han mantenido los precios en el nivel de 2017\u201d, inform\u00f3 el servicio de prensa de Intourist.<\/p>\n<p>La compa\u00f1\u00eda Biblio-Globus inform\u00f3 que el coste medio por persona de un tour de 7 noches con alojamiento en un hotel de 3* y desayuno ser\u00e1 de 21,6 mil rublos en Rusia, 30,7 mil en Chipre, 27,5 mil en Turqu\u00eda y 34,9 mil en Grecia.<\/p>\n<p>Tez Tour inform\u00f3 que los precios de los tours de mayo aumentaron un promedio de 3-5%, incluso debido a la diferencia en los tipos de cambio. \u201cLos viajes en mayo ofrecen una amplia gama de precios y preferencias; tanto las opciones econ\u00f3micas como las de lujo tienen gran demanda\u201d, se\u00f1al\u00f3 L. Akhanova.<\/p>\n<p>Este a\u00f1o, el fin de semana festivo para los rusos comenzar\u00e1 el domingo 29 de abril y durar\u00e1 hasta el mi\u00e9rcoles 2 de mayo inclusive. As\u00ed, la primera semana laboral del mes de mayo tendr\u00e1 una duraci\u00f3n de dos d\u00edas. Dentro de una semana, los rusos tendr\u00e1n d\u00eda libre el 9 de mayo, que este a\u00f1o cae en mi\u00e9rcoles. El d\u00eda festivo de descanso \u201cdividir\u00e1\u201d la semana laboral en dos partes: 7 y 8 de mayo (lunes y martes) y 10 y 11 de mayo (jueves y viernes).<\/p>\n<p>Como se inform\u00f3 anteriormente, en 2017 la demanda de viajes al extranjero entre los rusos aument\u00f3 en una cuarta parte.<\/p>\n<p>Fuente: <a href=\"http:\/\/tourism.interfax.ru\/ru\/analytics\/market_overview\/48286\/\" target=\"_blank\" rel=\"noopener\">turismo.interfax.ru<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>En particular, Marina Makarkova, directora del departamento de relaciones p\u00fablicas del operador tur\u00edstico Coral Travel, inform\u00f3 sobre el crecimiento de la popularidad de Turqu\u00eda en 50%.<\/p>","protected":false},"author":1,"featured_media":41958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[31,12,27,14,15,16,51,45,18,28],"class_list":["post-41957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analitika","tag-belarus","tag-gretsiya","tag-egipet","tag-ispaniya","tag-italiya","tag-kipr","tag-oae","tag-tailand","tag-tunis","tag-chehiya"],"_links":{"self":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/41957"}],"collection":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/comments?post=41957"}],"version-history":[{"count":0,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/41957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media\/41958"}],"wp:attachment":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media?parent=41957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/categories?post=41957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags?post=41957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}