{"id":43528,"date":"2018-05-04T00:01:05","date_gmt":"2018-05-03T21:01:05","guid":{"rendered":"https:\/\/dev.prestigtours.com\/novosti\/rossiian-predypredili-o-vspyshke-lihoradki-denge-v-tailande.html"},"modified":"2018-05-04T00:01:05","modified_gmt":"2018-05-03T21:01:05","slug":"rossiian-predypredili-o-vspyshke-lihoradki-denge-v-tailande","status":"publish","type":"post","link":"https:\/\/dev.prestigtours.com\/es\/novosti\/rossiian-predypredili-o-vspyshke-lihoradki-denge-v-tailande","title":{"rendered":"Los rusos advierten sobre el brote de dengue en Tailandia"},"content":{"rendered":"<p>\n<strong>Tailandia registra actualmente una emergencia epidemiol\u00f3gica por dengue. La situaci\u00f3n es especialmente grave en la isla de Phuket, donde se han registrado 220 casos desde principios de este a\u00f1o, seg\u00fan Rospotrebnadzor. <!--more--><\/strong><\/p>\n<p>\n<strong><\/p>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2018\/05\/b39b8241a33b52759719b7cf10bc6364.jpg\" \/><\/p>\n<p><\/strong><\/p>\n<p>\nTambi\u00e9n se han reportado casos de dengue en las provincias de Samut Sakhot, Phang Nga, Nakhon Sri Thamarat y Krabi. En lo que va de 2018, nueve casos han causado muertes en Tailandia, incluyendo dos en la isla de Phuket. El aumento de casos se debe a la estacionalidad de la epidemia (inicio de la temporada de monzones y calor intenso).<\/p>\n<p>\nEn los \u00faltimos a\u00f1os, se han registrado casos importados de dengue en la Federaci\u00f3n de Rusia: 63 casos en 2012, 170 en 2013, 105 en 2014, 136 en 2015, 145 en 2016, 196 en 2017 y 59 casos en el primer trimestre de 2018. Las infecciones se produjeron durante visitas a Tailandia, Vietnam, Indonesia, India, Bangladesh, Hong Kong y Maldivas, explic\u00f3 el departamento.<\/p>\n<p>\nEl principal portador del dengue es el mosquito Aedes aegypti. En ausencia de portador, una persona infectada no representa ning\u00fan riesgo epidemiol\u00f3gico.<\/p>\n<p>\n<strong>Como referencia:<\/strong><\/p>\n<p>\nEl dengue es una infecci\u00f3n viral transmitida por la picadura de mosquitos. Los s\u00edntomas incluyen fiebre alta, n\u00e1useas, sarpullido, dolor de cabeza y dolor de espalda. La forma hemorr\u00e1gica de la fiebre se acompa\u00f1a de hemorragia interna grave causada por el colapso de los vasos sangu\u00edneos.<\/p>\n<p>\nPara prevenir el dengue y otras fiebres hemorr\u00e1gicas transmitidas por contagio entre turistas rusos que viajan a Per\u00fa, Tailandia, Indonesia, India, Vietnam, Bangladesh, Hong Kong y otros pa\u00edses tropicales, es necesario:<\/p>\n<p>\n\u2022 al viajar a pa\u00edses de clima tropical, informarse sobre la posibilidad de contagio de fiebres hemorr\u00e1gicas de transmisi\u00f3n por contagio;<\/p>\n<p>\n\u2022 utilizar equipos de protecci\u00f3n personal como: mosquiteros, marquesinas, ropa de manga larga, materiales tratados con insecticidas, repelentes;<\/p>\n<p>\n\u2022 Al regresar, si su temperatura aumenta, informe a su m\u00e9dico sobre su estancia en un pa\u00eds con clima tropical.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.trn-news.ru\/news\/74180\" target=\"_blank\" rel=\"noopener\">trn-news.ru<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Actualmente se est\u00e1 registrando una emergencia epidemiol\u00f3gica por fiebre del dengue en Tailandia. La situaci\u00f3n es particularmente grave en la isla de Phuket, donde<\/p>","protected":false},"author":1,"featured_media":43529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[87,30,71,45],"class_list":["post-43528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novosti","tag-bangladesh","tag-vetnam","tag-peru","tag-tailand"],"_links":{"self":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/43528"}],"collection":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/comments?post=43528"}],"version-history":[{"count":0,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/43528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media\/43529"}],"wp:attachment":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media?parent=43528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/categories?post=43528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags?post=43528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}