{"id":55523,"date":"2018-09-26T08:02:32","date_gmt":"2018-09-26T05:02:32","guid":{"rendered":"https:\/\/dev.prestigtours.com\/novosti\/rostyrizm-zapyskaet-reklamnyu-kampaniu-v-azii.html"},"modified":"2018-09-26T08:02:32","modified_gmt":"2018-09-26T05:02:32","slug":"rostyrizm-zapyskaet-reklamnyu-kampaniu-v-azii","status":"publish","type":"post","link":"https:\/\/dev.prestigtours.com\/es\/novosti\/rostyrizm-zapyskaet-reklamnyu-kampaniu-v-azii","title":{"rendered":"Rostourism lanza campa\u00f1a publicitaria en Asia"},"content":{"rendered":"<p>\n<strong>La Agencia Federal de Turismo ha lanzado una campa\u00f1a de publicidad exterior en las megaciudades de China, Jap\u00f3n y la Rep\u00fablica de Corea. El proyecto ha elegido un formato inusual para atraer la atenci\u00f3n de una audiencia multimillonaria en Tokio, Hong Kong y Se\u00fal. A t\u00edtulo informativo <!--more-->Los medios de comunicaci\u00f3n en estas ciudades utilizan autom\u00f3viles privados cuyas superficies est\u00e1n cubiertas con pel\u00edculas de vinilo con im\u00e1genes que ilustran el atractivo tur\u00edstico de la Federaci\u00f3n Rusa.<\/strong><\/p>\n<p>\n<strong><\/p>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2018\/09\/fa83c03acbaeb8052a8f6b1a88f83f5b.jpg\" \/><\/p>\n<p><\/strong><\/p>\n<p>\nLa publicidad en veh\u00edculos privados es una nueva direcci\u00f3n en la publicidad exterior, que tiene una serie de ventajas adicionales, que incluyen una gran cantidad de contactos de informaci\u00f3n \u00fanicos y una amplia cobertura de audiencia debido al denso tr\u00e1fico en las megaciudades y el movimiento constante de autom\u00f3viles por las calles y carreteras de la ciudad, una alta probabilidad de familiarizaci\u00f3n detallada de la audiencia con el contenido publicitario, especialmente en atascos y sem\u00e1foros, mayor confianza en la informaci\u00f3n por parte de los consumidores, etc.<\/p>\n<p>\nLa campa\u00f1a publicitaria, que se desarrolla bajo el lema &quot;\u00bfHas visto eso?&quot; (\u00bfHas visto esto?) comenz\u00f3 en septiembre de 2018. En la actualidad, ya se utilizan alrededor de 100 autom\u00f3viles privados para promover las oportunidades tur\u00edsticas de Rusia, con im\u00e1genes atractivas y comprensibles en los laterales de los veh\u00edculos, que representan la naturaleza rusa, el arte cl\u00e1sico y las tradiciones.<\/p>\n<p>\nLos pa\u00edses de la regi\u00f3n Asia-Pac\u00edfico son mercados tur\u00edsticos en crecimiento y son muy prometedores en t\u00e9rminos de aumentar los flujos tur\u00edsticos entrantes a Rusia. El n\u00famero de turistas chinos, japoneses y coreanos que visitan la Federaci\u00f3n Rusa est\u00e1 creciendo constantemente. En particular, en 2017, el flujo tur\u00edstico entrante procedente de la Rep\u00fablica de Corea aument\u00f3 en 58% en comparaci\u00f3n con el a\u00f1o anterior, el de Jap\u00f3n en 21% y el de China en 15%. En el primer semestre de 2018, el n\u00famero de viajes tur\u00edsticos de ciudadanos coreanos a Rusia aument\u00f3 en 29% en comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior, y en 21% los de ciudadanos chinos.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.trn-news.ru\/news\/81608\" target=\"_blank\" rel=\"noopener\">trn-news.ru<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La Agencia Federal de Turismo ha lanzado una campa\u00f1a de publicidad exterior en las megaciudades de China, Jap\u00f3n y la Rep\u00fablica de Corea. El proyecto ha elegido un formato inusual para atraer la atenci\u00f3n de una empresa multimillonaria.<\/p>","protected":false},"author":1,"featured_media":55524,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[55],"class_list":["post-55523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novosti","tag-koreya"],"_links":{"self":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/55523"}],"collection":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/comments?post=55523"}],"version-history":[{"count":0,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/55523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media\/55524"}],"wp:attachment":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media?parent=55523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/categories?post=55523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags?post=55523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}