{"id":56509,"date":"2018-11-07T15:01:07","date_gmt":"2018-11-07T12:01:07","guid":{"rendered":"https:\/\/dev.prestigtours.com\/novosti\/moskva-priniala-pervyi-reis-iz-maskata.html"},"modified":"2018-11-07T15:01:07","modified_gmt":"2018-11-07T12:01:07","slug":"moskva-priniala-pervyi-reis-iz-maskata","status":"publish","type":"post","link":"https:\/\/dev.prestigtours.com\/es\/novosti\/moskva-priniala-pervyi-reis-iz-maskata","title":{"rendered":"Mosc\u00fa recibi\u00f3 el primer vuelo desde Mascate"},"content":{"rendered":"<p>\n<strong>El 31 de octubre Mosc\u00fa recibi\u00f3 el primer avi\u00f3n de pasajeros procedente de Mascate, marcando as\u00ed la apertura del servicio a\u00e9reo directo entre Rusia y Om\u00e1n.<\/strong><\/p>\n<p><p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2018\/11\/82fcc126458f39c3cbe53f9499e6db9c.jpg\" \/><\/p>\n<\/p>\n<p>\nMascate es la capital de Om\u00e1n, una ciudad portuaria en el Golfo de Om\u00e1n, rodeada de monta\u00f1as y desierto. Ahora los turistas podr\u00e1n... <!--more-->volar a esta ciudad en vuelos directos, y tambi\u00e9n regresar a Mosc\u00fa en la direcci\u00f3n opuesta.<\/p>\n<p>\nComo se\u00f1ala Rostourism, el intercambio tur\u00edstico entre Rusia y Om\u00e1n es actualmente insignificante. Sin embargo, cabe destacar que Om\u00e1n podr\u00eda ser de inter\u00e9s para los turistas rusos como destino de buceo y playa. Rusia, a su vez, tambi\u00e9n est\u00e1 dispuesta a ofrecer a los turistas oman\u00edes diversos tours de viaje, ocio y bienestar.<\/p>\n<p>\nEsta ruta ofrece una gran cantidad de oportunidades para los viajeros rusos: el aeropuerto de Mascate es un centro de tr\u00e1nsito (punto de transferencia de pasajeros) que recibe una gran cantidad de vuelos de conexi\u00f3n a India, Tailandia y otros pa\u00edses del sudeste asi\u00e1tico.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.trn-news.ru\/news\/83409\" target=\"_blank\" rel=\"noopener\">trn-news.ru<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El 31 de octubre, Mosc\u00fa recibi\u00f3 el primer avi\u00f3n de pasajeros procedente de Mascate, lo que marc\u00f3 el inicio del servicio a\u00e9reo directo entre Rusia y Om\u00e1n. Mascate es la capital de Om\u00e1n.<\/p>","protected":false},"author":1,"featured_media":56510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[150,26,45],"class_list":["post-56509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novosti","tag-oman","tag-rossiya","tag-tailand"],"_links":{"self":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/56509"}],"collection":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/comments?post=56509"}],"version-history":[{"count":0,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/56509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media\/56510"}],"wp:attachment":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media?parent=56509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/categories?post=56509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags?post=56509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}