{"id":56557,"date":"2018-11-09T01:01:08","date_gmt":"2018-11-08T22:01:08","guid":{"rendered":"https:\/\/dev.prestigtours.com\/novosti\/minzdrav-oae-raziasnil-kak-vvozit-lekarstva-v-strany.html"},"modified":"2018-11-09T01:01:08","modified_gmt":"2018-11-08T22:01:08","slug":"minzdrav-oae-raziasnil-kak-vvozit-lekarstva-v-strany","status":"publish","type":"post","link":"https:\/\/dev.prestigtours.com\/es\/novosti\/minzdrav-oae-raziasnil-kak-vvozit-lekarstva-v-strany","title":{"rendered":"El Ministerio de Salud de los EAU aclara c\u00f3mo importar medicamentos al pa\u00eds."},"content":{"rendered":"<p>\n<strong>La semana pasada, se inform\u00f3 en los medios que los Emiratos \u00c1rabes Unidos hab\u00edan impuesto la obligaci\u00f3n de que los turistas obtuvieran permiso para importar medicamentos antes de viajar. Sin embargo, el Ministerio de Salud de los EAU aclar\u00f3 que las normas para la importaci\u00f3n de medicamentos no han cambiado significativamente.<\/strong><\/p>\n<p>\n\u00a0<\/p>\n<p><p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2018\/11\/a79cc23ef0af0627b74a11857ea874f0.jpg\" \/><\/p>\n<\/p>\n<p>\n\u00a0<\/p>\n<p>\nPara los viajeros, <!--more-->Quienes necesiten transportar psicotr\u00f3picos u otros medicamentos recetados (prohibidos por la normativa aduanera) a o a trav\u00e9s de los EAU para uso personal deben declararlos previamente. Esto puede hacerse en el sitio web del Ministerio de Salud de los EAU a trav\u00e9s de este enlace (http:\/\/www.mohap.gov.ae\/en\/services\/Pages\/361.aspx). Primero, cree una cuenta en el sitio web del Ministerio de Salud y reg\u00edstrese como particular. Despu\u00e9s, cargue sus recetas y documentos m\u00e9dicos al sistema.<\/p>\n<p>\nEl Sr. Amin Hussein El Amiri, Director Adjunto del Departamento de Salud P\u00fablica y Licencias, record\u00f3 que los medicamentos pueden declararse directamente a la llegada al aeropuerto de Dubai, como se hac\u00eda anteriormente.<\/p>\n<p>\nEl \u00fanico cambio es el proceso de declaraci\u00f3n totalmente electr\u00f3nico y a distancia. No es obligatorio. Los turistas tambi\u00e9n pueden presentar sus documentos en el aeropuerto. Sin embargo, el nuevo servicio es muy pr\u00e1ctico, afirm\u00f3 el Sr. Amin Hussein El-Amiri.<\/p>\n<p>\nSeg\u00fan la normativa, la importaci\u00f3n de estupefacientes y psicotr\u00f3picos a los EAU requiere una receta m\u00e9dica certificada de una cl\u00ednica autorizada por el estado (original y copia), traducida al \u00e1rabe o al ingl\u00e9s, y documentos que certifiquen la autorizaci\u00f3n para el uso personal del medicamento. Es importante tener en cuenta que la cantidad del medicamento no debe exceder las 30 dosis diarias especificadas en la receta.<\/p>\n<p>\nAdem\u00e1s, seg\u00fan la normativa, los medicamentos y sus componentes no deben figurar en la lista de sustancias del Cap\u00edtulo IV de la Ley de Sustancias Narc\u00f3ticas de los EAU (1995) ni en las listas especiales del Ministerio de Salud de los EAU (listas CDA y CDB). La cantidad importada de dichos medicamentos no debe exceder un suministro de tres meses.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.trn-news.ru\/news\/83495\" target=\"_blank\" rel=\"noopener\">trn-news.ru<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La semana pasada, surgieron informes en los medios de comunicaci\u00f3n que indicaban que los Emiratos \u00c1rabes Unidos hab\u00edan exigido a los turistas obtener permiso para importar medicamentos antes de viajar. Sin embargo, el Ministerio de Salud explic\u00f3<\/p>","protected":false},"author":1,"featured_media":56558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[51],"class_list":["post-56557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novosti","tag-oae"],"_links":{"self":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/56557"}],"collection":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/comments?post=56557"}],"version-history":[{"count":0,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/56557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media\/56558"}],"wp:attachment":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media?parent=56557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/categories?post=56557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags?post=56557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}