{"id":56963,"date":"2018-11-25T06:01:08","date_gmt":"2018-11-25T03:01:08","guid":{"rendered":"https:\/\/dev.prestigtours.com\/stati\/kak-yvidet-iaponiu-i-ujnyu-koreu-za-odno-pyteshestvie.html"},"modified":"2018-11-25T06:01:08","modified_gmt":"2018-11-25T03:01:08","slug":"kak-yvidet-iaponiu-i-ujnyu-koreu-za-odno-pyteshestvie","status":"publish","type":"post","link":"https:\/\/dev.prestigtours.com\/es\/stati\/kak-yvidet-iaponiu-i-ujnyu-koreu-za-odno-pyteshestvie","title":{"rendered":"C\u00f3mo ver Jap\u00f3n y Corea del Sur en un solo viaje"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft\" src=\"\/wp-content\/uploads\/2018\/11\/3ca0c3a6f00e1c64d6766f64505d85c2.jpg\" \/><\/p>\n<p>Foto: La vuelta al mundo<\/p>\n<p>Se ha lanzado una nueva ruta tur\u00edstica en Asia que combina visitas a las ciudades y atracciones de Corea del Sur y Jap\u00f3n, escribe Travel Weekly.<\/p>\n<p>La compa\u00f1\u00eda de viajes Saga ha anunciado el lanzamiento de un nuevo tour de 13 d\u00edas Esencia de Corea del Sur y Jap\u00f3n en 2019. <!--more-->La pen\u00ednsula de Corea y Jap\u00f3n. Esta ruta est\u00e1 dise\u00f1ada para viajeros que desean conocer dos culturas \u00fanicas del mundo a la vez. Durante el viaje, los turistas podr\u00e1n visitar las ciudades surcoreanas de Gyeongju y Busan, as\u00ed como la capital, Se\u00fal. El programa incluye recorridos tur\u00edsticos, una visita al mirador de la Torre de Televisi\u00f3n de Se\u00fal, el Palacio Gyeongbok, el antiguo observatorio astron\u00f3mico Cheomseongdae, la playa de arena de 1,5 kil\u00f3metros de Haeundae en Busan y monumentos de la Guerra de Corea. El programa tambi\u00e9n incluye un viaje a la zona desmilitarizada, donde tuvo lugar el sensacional encuentro del l\u00edder norcoreano Kim Jong-un con el presidente surcoreano Luna Jae. La parte japonesa del recorrido incluye excursiones a Kioto y Tokio, observaci\u00f3n del Monte Fuji, una visita al lago volc\u00e1nico Ashi, el telef\u00e9rico m\u00e1s alto de Jap\u00f3n, Komagatake, los templos de Kiyomizu, Ronaji y Kinkakuji, as\u00ed como jardines con sakura en flor. Ning\u00fan viaje estar\u00eda completo sin un paseo en los trenes de alta velocidad de Jap\u00f3n.<\/p>\n<p>La nueva ruta tambi\u00e9n ofrece numerosas oportunidades para los amantes de la gastronom\u00eda. El recorrido ense\u00f1ar\u00e1 a los viajeros a preparar sushi japon\u00e9s y aut\u00e9ntico pollo frito coreano, e incluir\u00e1 una cena tradicional de yakitori, casas de t\u00e9 y restaurantes con tem\u00e1tica ninja y de sumo.<\/p>\n<p>Actualmente hay cuatro fechas disponibles para reservar la gira Esencia de Corea del Sur y Jap\u00f3n: 2 de septiembre y 28 de octubre de 2019, 18 de marzo y 4 de mayo de 2020. Los precios parten de 4500 \u20ac por persona, que incluye seguro, alojamiento en hotel, vuelo nocturno de Busan a Osaka y comidas.<\/p>\n<p>Fuente: <a href=\"http:\/\/news.turizm.ru\/japan\/59089\" target=\"_blank\" rel=\"noopener\">noticias.turizm.ru<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Foto: La Vuelta al Mundo Se ha lanzado una nueva ruta tur\u00edstica en Asia que combina visitas a las ciudades y atracciones de Corea del Sur y Jap\u00f3n.<\/p>","protected":false},"author":1,"featured_media":56964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-56963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stati"],"_links":{"self":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/56963"}],"collection":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/comments?post=56963"}],"version-history":[{"count":0,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/56963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media\/56964"}],"wp:attachment":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media?parent=56963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/categories?post=56963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags?post=56963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}