{"id":57358,"date":"2018-12-12T09:01:09","date_gmt":"2018-12-12T06:01:09","guid":{"rendered":"https:\/\/dev.prestigtours.com\/novosti\/jemchyjnaia-reka-prodoljit-otpravliat-tyristov-na-hainan.html"},"modified":"2018-12-12T09:01:09","modified_gmt":"2018-12-12T06:01:09","slug":"jemchyjnaia-reka-prodoljit-otpravliat-tyristov-na-hainan","status":"publish","type":"post","link":"https:\/\/dev.prestigtours.com\/es\/novosti\/jemchyjnaia-reka-prodoljit-otpravliat-tyristov-na-hainan","title":{"rendered":"El r\u00edo Perla seguir\u00e1 enviando turistas a Hainan."},"content":{"rendered":"<p>\nPearl River continuar\u00e1 transportando turistas a la isla china de Hainan. El programa de vuelos de la compa\u00f1\u00eda ser\u00e1 operado por Alrosa Airlines, seg\u00fan inform\u00f3 a TRN el servicio de prensa del operador tur\u00edstico.<\/p>\n<p>\n\u00a0<\/p>\n<p><p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2018\/12\/097eb5cca364e1cf1f79c71fdef571c8.jpg\" \/><\/p>\n<\/p>\n<p>\n\u00a0<\/p>\n<p>\n\u201cLos turistas que han pagado tours con transporte <!--more-->Los pasajeros de IrAero que no hayan disfrutado de sus vacaciones podr\u00e1n cancelar sus viajes y recibir un reembolso completo del operador tur\u00edstico, o volar a su destino vacacional desde otras ciudades con Alrosa Airlines. Alrosa opera vuelos a Hainan en nombre de Pearl River Airlines desde las siguientes ciudades: Blagov\u00e9shchensk, Chita, Barnaul, Novokuznetsk, Tomsk y K\u00e9merovo, explic\u00f3 el servicio de prensa de la compa\u00f1\u00eda.<\/p>\n<p>\nComo recordatorio, el viernes pasado, IrAero Airlines anunci\u00f3 la suspensi\u00f3n de los vuelos a Sanya y Haikou, as\u00ed como de los vuelos para turistas del R\u00edo de las Perlas en todas las rutas previamente acordadas, incluyendo Jab\u00e1rovsk, Cheli\u00e1binsk, Uf\u00e1, San Petersburgo, Samara, Kaz\u00e1n, K\u00e9merovo y Mosc\u00fa. El servicio de prensa de la aerol\u00ednea aclar\u00f3 que la suspensi\u00f3n se deb\u00eda a las deudas pendientes del operador tur\u00edstico.<\/p>\n<p>\n\u00a0<\/p>\n<p>Fuente: <a href=\"http:\/\/www.trn-news.ru\/news\/84926\" target=\"_blank\" rel=\"noopener\">trn-news.ru<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Pearl River continuar\u00e1 transportando turistas a la isla china de Hainan. El programa de vuelos de la compa\u00f1\u00eda ser\u00e1 operado por Alrosa Airlines, seg\u00fan inform\u00f3 el servicio de prensa de la compa\u00f1\u00eda a TRN.<\/p>","protected":false},"author":1,"featured_media":57359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-57358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novosti"],"_links":{"self":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/57358"}],"collection":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/comments?post=57358"}],"version-history":[{"count":0,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/57358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media\/57359"}],"wp:attachment":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media?parent=57358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/categories?post=57358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags?post=57358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}