{"id":62691,"date":"2019-12-20T20:01:31","date_gmt":"2019-12-20T17:01:31","guid":{"rendered":"https:\/\/dev.prestigtours.com\/novosti\/registraciia-na-konkyrs-mastera-gostepriimstva-prodlena-do-29-dekabria.html"},"modified":"2019-12-20T20:01:31","modified_gmt":"2019-12-20T17:01:31","slug":"registraciia-na-konkyrs-mastera-gostepriimstva-prodlena-do-29-dekabria","status":"publish","type":"post","link":"https:\/\/dev.prestigtours.com\/es\/novosti\/registraciia-na-konkyrs-mastera-gostepriimstva-prodlena-do-29-dekabria","title":{"rendered":"La inscripci\u00f3n para el concurso Masters of Hospitality se ha ampliado hasta el 29 de diciembre."},"content":{"rendered":"<p>\n<strong>Campa\u00f1a de solicitud para el concurso de toda Rusia <\/strong><strong>Maestros de la Hospitalidad<\/strong><strong>\u00a0\u2014 uno de los proyectos de la plataforma presidencial <\/strong><strong>&quot;Rusia es un pa\u00eds de oportunidades<\/strong><strong>\u00bb<\/strong><strong>\u00a0\u2014 prorrogado hasta el 29 de diciembre de 2019. Para participar en el concurso es necesario registrarse en la web del proyecto. <!--more--><\/strong><strong>https:\/\/welcomecup.ru\/<\/strong><strong>.<\/strong><\/p>\n<p>\n\u00a0<\/p>\n<p><p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2019\/12\/032886f8e489e23822d96d8032ca8df3.jpg\" \/><\/p>\n<\/p>\n<p>\n\u00a0<\/p>\n<p>\nHasta el momento, se han presentado m\u00e1s de 15.000 solicitudes al concurso desde las 85 regiones de Rusia. Las m\u00e1s activas fueron la Rep\u00fablica de Baskortost\u00e1n y Crimea, Mosc\u00fa, San Petersburgo y la regi\u00f3n de N\u00f3vgorod. De los participantes, 65.313 fueron mujeres y 34.713 hombres. Personas de todas las edades y profesiones presentaron sus solicitudes, lo que demuestra una vez m\u00e1s que la industria hotelera est\u00e1 abierta a todos los que quieran poner a prueba sus habilidades. Debido al alto nivel de participaci\u00f3n, hemos decidido extender el plazo de inscripci\u00f3n hasta las 23:59 (hora de Mosc\u00fa) del 29 de diciembre para que todos los representantes del sector hotelero puedan presentar sus solicitudes, se\u00f1al\u00f3 el responsable de relaciones con socios de ANO &quot;Rusia, Tierra de Oportunidades&quot;. <strong>Ant\u00f3n Serikov.<\/strong><\/p>\n<p>\n&quot;Recibimos solicitudes de personas de diversos sectores industriales. Aproximadamente un tercio de los participantes son jefes de departamento, gerentes, directores creativos y due\u00f1os de negocios. El 65,61 % de los participantes tiene uno o m\u00e1s t\u00edtulos de educaci\u00f3n superior, mientras que el 19,91 % tiene educaci\u00f3n secundaria o profesional&quot;, explic\u00f3 el director del concurso &quot;Maestr\u00eda en Hosteler\u00eda&quot;. <strong>Evgeny Malygin. <\/strong>Queremos brindarle al mayor n\u00famero posible de personas la oportunidad de descubrir su talento y hacerse un nombre en la industria hotelera. Cualquier competencia se centra en el desarrollo personal. Solo al comprender tu potencial y encontrar la fuerza para superar las barreras podr\u00e1s desarrollarte, incluso profesionalmente. Nuestra competencia es para aquellos cuyas vidas est\u00e1n inextricablemente ligadas al turismo y la hoteler\u00eda, la mejor profesi\u00f3n del mundo.<\/p>\n<p>\n<strong>Concurso profesional de toda Rusia &quot;Maestros de la Hosteler\u00eda&quot;<\/strong> El concurso se lanz\u00f3 el 13 de noviembre. El objetivo del proyecto es impulsar el potencial de los profesionales, fomentar nuevas tradiciones y elevar los est\u00e1ndares de servicio y el prestigio de las profesiones en los sectores del turismo y la hosteler\u00eda. Adem\u00e1s de los conocimientos y las competencias de los participantes, el concurso tambi\u00e9n evaluar\u00e1 sus proyectos hoteleros originales. Los mejores proyectos recibir\u00e1n apoyo y se implementar\u00e1n en las regiones rusas. El concurso est\u00e1 coorganizado por <strong>Sindicato Nacional de la Industria Hotelera (NUHI). <\/strong><\/p>\n<p>\nSe elegir\u00e1n cincuenta concursantes ganadores. Todos tendr\u00e1n la oportunidad de participar en un programa de mentor\u00eda con l\u00edderes de la industria y funcionarios gubernamentales. Veinticinco de ellos tambi\u00e9n recibir\u00e1n un certificado para un programa educativo especial en la Escuela de Administraci\u00f3n Skolkovo de Mosc\u00fa. Todos los finalistas tambi\u00e9n podr\u00e1n recibir invitaciones a pr\u00e1cticas profesionales en agencias gubernamentales, empresas l\u00edderes y organizaciones.<\/p>\n<p>\nEl concurso &quot;Maestros de la Hospitalidad&quot; se desarrollar\u00e1 en varias etapas: rondas de inscripci\u00f3n y clasificaci\u00f3n, semifinales regionales y la final. Para participar, reg\u00edstrate en la p\u00e1gina web del concurso http:\/\/welcomecup.ru\/, completa el formulario antes del 29 de diciembre y sube tu video de saludo con tu ciudad, regi\u00f3n u otra atracci\u00f3n tur\u00edstica rusa favorita.<\/p>\n<p>\nLa ronda de selecci\u00f3n (prueba en l\u00ednea) del concurso tendr\u00e1 lugar en enero-febrero de 2020. Durante esta ronda, los expertos del concurso evaluar\u00e1n los conocimientos generales y profesionales, las capacidades intelectuales y las competencias de gesti\u00f3n.<\/p>\n<p>\nLas semifinales regionales se celebrar\u00e1n de febrero a abril en nueve regiones de Rusia. La final tendr\u00e1 lugar en abril de 2020 y reunir\u00e1 a 200 especialistas del sector.<\/p>\n<p>\nCualquiera puede participar en el concurso, competir por premios y recibir una beca para implementar su propio proyecto. Los participantes deben ser ciudadanos rusos y mayores de 18 a\u00f1os. Los ganadores se emparejar\u00e1n con restauradores, hoteleros y gerentes de hosteler\u00eda de renombre.<\/p>\n<p>\nLos mejores proyectos del concurso podr\u00e1n realizarse con el apoyo de la Compa\u00f1\u00eda Federal de Pasajeros, Rostourism y el Ministerio de Recursos Naturales y Medio Ambiente de la Federaci\u00f3n de Rusia.<\/p>\n<p>\nLos participantes tambi\u00e9n tendr\u00e1n la oportunidad de ganar viajes al hotel de cinco estrellas MRIYA RESORT &amp; SPA, un curso de ingl\u00e9s de negocios de Skyeng, formaci\u00f3n en Travel Business School, apoyo a los mejores proyectos del servicio de viajes n\u00famero uno de Rusia, Tutu.ru, un valioso premio de METRO Cash&amp;Carry, certificados de Sletat.ru Academy y mucho m\u00e1s.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.trn-news.ru\/news\/98411\" target=\"_blank\" rel=\"noopener\">trn-news.ru<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El plazo de solicitud para el concurso panruso &quot;Maestros de la Hospitalidad&quot; \u2014uno de los proyectos de la plataforma presidencial &quot;Rusia - Tierra de Oportunidades&quot;\u2014 se ha prorrogado hasta el 29 de diciembre de 2019. Para convertirse en<\/p>","protected":false},"author":1,"featured_media":62692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-62691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novosti"],"_links":{"self":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/62691"}],"collection":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/comments?post=62691"}],"version-history":[{"count":0,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts\/62691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media\/62692"}],"wp:attachment":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/media?parent=62691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/categories?post=62691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags?post=62691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}