{"id":187,"count":1,"description":"","link":"https:\/\/dev.prestigtours.com\/es\/tag\/benin","name":"\u0411\u0435\u043d\u0438\u043d","slug":"benin","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags\/187"}],"collection":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dev.prestigtours.com\/es\/wp-json\/wp\/v2\/posts?tags=187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}